{"id":548,"count":164,"description":"Posts related to the Classics Library.","link":"https:\/\/libapps.libraries.uc.edu\/liblog\/category\/classics\/","name":"Classics Library","slug":"classics","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/libapps.libraries.uc.edu\/liblog\/wp-json\/wp\/v2\/categories\/548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libapps.libraries.uc.edu\/liblog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/libapps.libraries.uc.edu\/liblog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/libapps.libraries.uc.edu\/liblog\/wp-json\/wp\/v2\/posts?categories=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}